{"id":6837,"date":"2023-11-16T13:46:59","date_gmt":"2023-11-16T13:46:59","guid":{"rendered":"https:\/\/demo.wpzoom.com\/inspiro-lite-blocks-xml\/?page_id=6837"},"modified":"2026-04-15T13:58:47","modified_gmt":"2026-04-15T13:58:47","slug":"about-2","status":"publish","type":"page","link":"https:\/\/terrazul.org\/wordpress_U\/index.php\/about-2\/","title":{"rendered":"Un poco m\u00e1s sobre Terrazul"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-default has-global-padding is-layout-constrained wp-container-core-group-is-layout-02ab25f7 wp-block-group-is-layout-constrained\" style=\"padding-top:60px;padding-bottom:60px;padding-left:0\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-d7d455e7 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"992\" src=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/4-fotos.png\" alt=\"\" class=\"wp-image-7312\" srcset=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/4-fotos.png 1000w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/4-fotos-300x298.png 300w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/4-fotos-150x150.png 150w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-left:var(--wp--preset--spacing--80);flex-basis:50%\">\n<p class=\"has-text-color\" style=\"color:#0bb4aa\">Nuestra Experiencia<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Un camino que inicio con el siglo.<\/h2>\n\n\n\n<p>Hemos caminado junto a comunidades way\u00fau, afro y campesinas de todo Colombia, tejiendo soluciones que nacen del territorio. Nuestra trayectoria combina innovaci\u00f3n tecnol\u00f3gica, biotecnolog\u00eda y sabidur\u00eda ancestral para generar impacto real y sostenible.<\/p>\n\n\n\n<p>El respaldo de entidades gubernamentales y privadas, nacionales e internacionales, ha sido fundamental. Hoy, nuestros proyectos en soberan\u00eda h\u00eddrica, seguridad alimentaria, regeneraci\u00f3n ambiental as\u00ed como proyectos productivos son prueba viva de que la transformaci\u00f3n es posible cuando se trabaja con la gente, no para la gente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#0bb4aa\">Lo que nosotros hacemos<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-large-font-size\">Traer un mundo de soluciones a las comunidades que las necesitan<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-outermost-icon-block aligncenter items-justified-left\"><div class=\"icon-container has-icon-color\" style=\"color:#0bb4aa;width:48px;transform:rotate(0deg) scaleX(1) scaleY(1)\"><svg width=\"50\" height=\"50\" viewBox=\"0 0 50 50\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M50 27.7778H31.6667L44.7222 40.8333L40.8333 44.7222L27.7778 31.6667V50H22.2222V31.3889L9.16667 44.4444L5.27778 40.5556L17.7778 27.7778H0V22.2222H18.3333L5.27778 9.16667L9.16667 5.27778L22.2222 18.3333V0H27.7778V17.7778L40.5556 5L44.4444 9.16667L31.3889 22.2222H50V27.7778Z\" fill=\"var(--wp--preset--color--primary)\"><\/path><\/svg><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Capacitaci\u00f3n<\/h2>\n\n\n\n<p>Lo que nos diferencia es nuestra permanencia en el territorio y nuestro respeto por las culturas locales. No imponemos soluciones. Las construimos junto a las comunidades, con sus saberes y sus tradiciones. <\/p>\n\n\n\n<p>Cada proyecto que realizamos:<br>\u2705 Es dise\u00f1ado con participaci\u00f3n comunitaria.<br>\u2705 Utiliza energ\u00edas limpias y tecnolog\u00eda apropiada.<br>\u2705 Genera capacidades locales para garantizar sostenibilidad.<br>\u2705 Se mide con indicadores claros de impacto.<\/p>\n\n\n\n<p><a href=\"https:\/\/terrazul.org\/wordpress_U\/index.php\/services\/\">Learn more \u2192<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-outermost-icon-block aligncenter items-justified-left\"><div class=\"icon-container has-icon-color\" style=\"color:#0bb4aa;width:48px;transform:rotate(0deg) scaleX(1) scaleY(1)\"><svg width=\"50\" height=\"50\" viewBox=\"0 0 50 50\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M50 27.7778H31.6667L44.7222 40.8333L40.8333 44.7222L27.7778 31.6667V50H22.2222V31.3889L9.16667 44.4444L5.27778 40.5556L17.7778 27.7778H0V22.2222H18.3333L5.27778 9.16667L9.16667 5.27778L22.2222 18.3333V0H27.7778V17.7778L40.5556 5L44.4444 9.16667L31.3889 22.2222H50V27.7778Z\" fill=\"var(--wp--preset--color--primary)\"><\/path><\/svg><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Consultor\u00eda<\/h2>\n\n\n\n<p>Trabajamos con comunidades ind\u00edgenas y campesinas en situaci\u00f3n de vulnerabilidad. Pero tambi\u00e9n somos socios estrat\u00e9gicos de:<\/p>\n\n\n\n<p>\u00b7 Organizaciones gubernamentales (locales, regionales, nacionales).<br>\u00b7 Agencias de cooperaci\u00f3n internacional.<br>\u00b7 Empresas privadas con programas de RSC y sostenibilidad.<\/p>\n\n\n\n<p><a href=\"https:\/\/terrazul.org\/wordpress_U\/index.php\/services\/\">Learn more \u2192<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-outermost-icon-block aligncenter items-justified-left\"><div class=\"icon-container has-icon-color\" style=\"color:#0bb4aa;width:48px;transform:rotate(0deg) scaleX(1) scaleY(1)\"><svg width=\"50\" height=\"50\" viewBox=\"0 0 50 50\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M50 27.7778H31.6667L44.7222 40.8333L40.8333 44.7222L27.7778 31.6667V50H22.2222V31.3889L9.16667 44.4444L5.27778 40.5556L17.7778 27.7778H0V22.2222H18.3333L5.27778 9.16667L9.16667 5.27778L22.2222 18.3333V0H27.7778V17.7778L40.5556 5L44.4444 9.16667L31.3889 22.2222H50V27.7778Z\" fill=\"var(--wp--preset--color--primary)\"><\/path><\/svg><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Desarrollo <\/h2>\n\n\n\n<p>Si tu organizaci\u00f3n busca invertir en proyectos con impacto verificable, gobernanza transparente y equipo t\u00e9cnico en terreno, Terrazul es tu aliado.<\/p>\n\n\n\n<p><br>\ud83d\udd17 Explora nuestros Servicios<br>Conoce las soluciones tecnol\u00f3gicas que ofrecemos, los proyectos que hemos desarrollado y c\u00f3mo podemos trabajar juntos.<\/p>\n\n\n\n<p><a href=\"#https:\/\/terrazul.org\/wordpress_U\/index.php\/services\/\">Learn more \u2192<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"team\" class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:74px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Our Team<\/h2>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<figure class=\"wp-block-image size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"395\" height=\"582\" src=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/henny-3.jpeg\" alt=\"\" class=\"wp-image-7184\" srcset=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/henny-3.jpeg 395w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2026\/04\/henny-3-204x300.jpeg 204w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Henny Tirado<\/h3>\n\n\n\n<p>CEO<\/p>\n\n\n\n<p>Nuestra CEO, lidera con experiencia en planeaci\u00f3n y ejecuci\u00f3n de programas para comunidades ind\u00edgenas. Su enfoque participativo fortalece la autogesti\u00f3n, seguridad alimentaria y desarrollo organizativo, promoviendo autonom\u00eda, equidad y sostenibilidad para el bienestar comunitario<\/p>\n\n\n\n<ul class=\"wp-block-social-links has-icon-color is-style-logos-only is-layout-flex wp-container-core-social-links-is-layout-327fadc6 wp-block-social-links-is-layout-flex\"><li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-instagram has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-linkedin has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/ruben-mindiola-web.jpg\" alt=\"\" class=\"wp-image-7094\" srcset=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/ruben-mindiola-web.jpg 1200w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/ruben-mindiola-web-225x300.jpg 225w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/ruben-mindiola-web-768x1024.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ruben Mindiola<\/h3>\n\n\n\n<p>Coordinador de Proyecto<\/p>\n\n\n\n<p>Rub\u00e9n Mindiola combina su expertise en zootecnia y energ\u00eda solar con una profunda experiencia de trabajo en terreno, liderando proyectos productivos y fortaleciendo comunidades wayuu y campesinas con soluciones t\u00e9cnicas y sociales integradas.<\/p>\n\n\n\n<p><a href=\"https:\/\/terrazul.org\/wordpress_U\/#\"><\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/terrazul.org\/wordpress_U\/#\">LinkedIn<\/a><\/p>\n\n\n\n<ul class=\"wp-block-social-links has-icon-color is-style-logos-only is-layout-flex wp-container-core-social-links-is-layout-5f86147d wp-block-social-links-is-layout-flex\"><li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-twitter has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M22.23,5.924c-0.736,0.326-1.527,0.547-2.357,0.646c0.847-0.508,1.498-1.312,1.804-2.27 c-0.793,0.47-1.671,0.812-2.606,0.996C18.324,4.498,17.257,4,16.077,4c-2.266,0-4.103,1.837-4.103,4.103 c0,0.322,0.036,0.635,0.106,0.935C8.67,8.867,5.647,7.234,3.623,4.751C3.27,5.357,3.067,6.062,3.067,6.814 c0,1.424,0.724,2.679,1.825,3.415c-0.673-0.021-1.305-0.206-1.859-0.513c0,0.017,0,0.034,0,0.052c0,1.988,1.414,3.647,3.292,4.023 c-0.344,0.094-0.707,0.144-1.081,0.144c-0.264,0-0.521-0.026-0.772-0.074c0.522,1.63,2.038,2.816,3.833,2.85 c-1.404,1.1-3.174,1.756-5.096,1.756c-0.331,0-0.658-0.019-0.979-0.057c1.816,1.164,3.973,1.843,6.29,1.843 c7.547,0,11.675-6.252,11.675-11.675c0-0.178-0.004-0.355-0.012-0.531C20.985,7.47,21.68,6.747,22.23,5.924z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Twitter<\/span><\/a><\/li>\n\n<li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-linkedin has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-default is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/Ana-Mery-web-edited.jpg\" alt=\"\" class=\"wp-image-7097\" srcset=\"https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/Ana-Mery-web-edited.jpg 600w, https:\/\/terrazul.org\/wordpress_U\/wp-content\/uploads\/2025\/10\/Ana-Mery-web-edited-225x300.jpg 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ana Mery Contreras<\/h3>\n\n\n\n<p>Biotecn\u00f3loga<\/p>\n\n\n\n<p>Desde corta edad ah trabajado en el desarrollo biotecnol\u00f3gico de programas relacionados con soberan\u00eda alimentaria y cultivo de super alimentos como Spirulina con un gran impacto en comunidades vulnerables.<\/p>\n\n\n\n<ul class=\"wp-block-social-links has-icon-color is-style-logos-only is-layout-flex wp-container-core-social-links-is-layout-5f86147d wp-block-social-links-is-layout-flex\"><li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-instagram has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li style=\"color:currentColor;\" class=\"wp-social-link wp-social-link-linkedin has-primary-color wp-block-social-link\"><a href=\"#\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:63px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Experiencia Un camino que inicio con el siglo. Hemos caminado junto a comunidades way\u00fau, afro y campesinas de todo Colombia, tejiendo soluciones que nacen del territorio. Nuestra trayectoria combina innovaci\u00f3n tecnol\u00f3gica, biotecnolog\u00eda y sabidur\u00eda ancestral para generar impacto real y sostenible. El respaldo de entidades gubernamentales y privadas, nacionales e internacionales, ha sido fundamental. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/terrazul.org\/wordpress_U\/index.php\/about-2\/\" class=\"more-link\">Read more<span class=\"screen-reader-text\"> &#8220;Un poco m\u00e1s sobre Terrazul&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inspiro_hide_title":false,"footnotes":""},"class_list":["post-6837","page","type-page","status-publish","hentry"],"featured_media_urls":[],"_links":{"self":[{"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/pages\/6837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/comments?post=6837"}],"version-history":[{"count":8,"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/pages\/6837\/revisions"}],"predecessor-version":[{"id":7323,"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/pages\/6837\/revisions\/7323"}],"wp:attachment":[{"href":"https:\/\/terrazul.org\/wordpress_U\/index.php\/wp-json\/wp\/v2\/media?parent=6837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}